{"id":37482,"date":"2024-04-16T14:48:16","date_gmt":"2024-04-16T11:48:16","guid":{"rendered":"https:\/\/www.4eyes.com.tr\/?p=37482"},"modified":"2024-04-16T16:32:01","modified_gmt":"2024-04-16T13:32:01","slug":"kylie-jenner-4","status":"publish","type":"post","link":"https:\/\/www.4eyes.com.tr\/en\/kylie-jenner-4\/","title":{"rendered":"Kylie Jenner"},"content":{"rendered":"\n  \n    <div id=\"gallery-1366079746\" class=\"row degrad lightbox-multi-gallery large-columns-2 medium-columns- small-columns- row-small row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/13-2.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image box-shadow-2 image-cover\" style=\"padding-top:120%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"450\" src=\"https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/13-2.jpg\" class=\"degrad\" alt=\"\" ids=\"37401,37403\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"2\" depth=\"2\" image_height=\"120%\" image_size=\"original\" image_overlay=\"rgba(255, 255, 255, 0)\" text_bg=\"rgba(255, 255, 255, 0)\" srcset=\"https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/13-2.jpg 375w, https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/13-2-250x300.jpg 250w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(255, 255, 255, 0)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" style=\"background-color:rgba(255, 255, 255, 0);\">\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/55.jpg\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image box-shadow-2 image-cover\" style=\"padding-top:120%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"450\" src=\"https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/55.jpg\" class=\"degrad\" alt=\"\" ids=\"37401,37403\" style=\"none\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"small\" columns=\"2\" depth=\"2\" image_height=\"120%\" image_size=\"original\" image_overlay=\"rgba(255, 255, 255, 0)\" text_bg=\"rgba(255, 255, 255, 0)\" srcset=\"https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/55.jpg 375w, https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/55-250x300.jpg 250w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(255, 255, 255, 0)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" style=\"background-color:rgba(255, 255, 255, 0);\">\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t<div id=\"text-3555405080\" class=\"text\">\n\t\t\n<h1>Kylie Jenner<\/h1>\n\t\t\n<style>\n#text-3555405080 {\n  font-size: 1rem;\n  line-height: 0.75;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2310350311\" class=\"text\">\n\t\t\n<h2 class=\"thin-font\">Metzler<\/h2>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -38px; top: -4.88281px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n\t\t\n<style>\n#text-2310350311 {\n  line-height: 0.75;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<p style=\"text-align: justify;\">Kylie Jenner, one of the iconic top models, is among the celebrities who appear with very different clothing styles. The optical frame she chose from Metzler suits Kylie Jenner extremely well.<\/p>\n<p style=\"text-align: right;\"><strong><span style=\"font-size: 85%;\">April 2024<\/span><\/strong><\/p>\n<div class=\"row\"  id=\"row-228134276\">\n\n\t<div id=\"col-1379865956\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2102692596\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1024714142\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/www.4eyes.com.tr\/wp-content\/uploads\/2024\/04\/Metzler.jpg\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1024714142 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1632452201\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kylie Jenner, one of the iconic top models, is among the celebrities who appear with very different clothing styles. The optical frame she chose from Metzler suits Kylie Jenner extremely well. April 2024<\/p>\n","protected":false},"author":4,"featured_media":37397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[319],"tags":[],"class_list":["post-37482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unlutercih-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/posts\/37482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/comments?post=37482"}],"version-history":[{"count":1,"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/posts\/37482\/revisions"}],"predecessor-version":[{"id":37504,"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/posts\/37482\/revisions\/37504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/media\/37397"}],"wp:attachment":[{"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/media?parent=37482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/categories?post=37482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.4eyes.com.tr\/en\/wp-json\/wp\/v2\/tags?post=37482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}